{"id":953,"date":"2016-04-08T14:00:18","date_gmt":"2016-04-08T12:00:18","guid":{"rendered":"http:\/\/hosting6807.af944.netcup.net\/?page_id=953"},"modified":"2024-09-14T15:37:55","modified_gmt":"2024-09-14T13:37:55","slug":"eintritt-in-die-erlebnisausstellung","status":"publish","type":"page","link":"https:\/\/www.hausamstrom.de\/de\/programm\/buchbares\/dauerbrenner\/eintritt-in-die-erlebnisausstellung\/","title":{"rendered":"Eintritt in die Erlebnisausstellung"},"content":{"rendered":"<p>Natur, Energie und Wasser sind die Leitthemen des Haus am Strom. Das erkennt man schon an der Architektur des Hauses, welche einer Donauwelle gleicht. Lernen Sie spielerisch die Artenvielfalt in den Donauleiten kennen, beobachten Sie eine Smaragdeidechse und erzeugen Sie Ihren eigenen Strom!<\/p>\n<p>\u00a0<\/p>\n<p><strong>Preise f\u00fcr Eintritt:<\/strong><\/p>\n<p>\u2013 f\u00fcr Erwachsene: 5,00 \u20ac<\/p>\n<p>\u2013 f\u00fcr Kinder (bis 14 Jahre) und Schwerbehinderte: 3,00 \u20ac<\/p>\n<p>\u2013 Gruppenerm\u00e4\u00dfigung ab 20 Personen (Erwachsene): 4,00 \u20ac pro Person<\/p>\n<p>\u2013 Gruppenerm\u00e4\u00dfigung ab 20 Personen (Kinder): 2,50 \u20ac pro Kind<\/p>\n<p>\u2013 Familienkarte mit 1 Kind: 10,00\u20ac (f\u00fcr jedes weitere Kind: 0,50 \u20ac)<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Natur, Energie und Wasser sind die Leitthemen des Haus am Strom. Das erkennt man schon an der Architektur des Hauses, welche einer Donauwelle gleicht. Lernen Sie spielerisch die Artenvielfalt in den Donauleiten kennen, beobachten Sie eine Smaragdeidechse und erzeugen Sie Ihren eigenen Strom! \u00a0 Preise f\u00fcr Eintritt: \u2013 f\u00fcr Erwachsene: 5,00 \u20ac \u2013 f\u00fcr Kinder [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":365,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-953","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eintritt in die Erlebnisausstellung - Haus am Strom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hausamstrom.de\/de\/programm\/buchbares\/dauerbrenner\/eintritt-in-die-erlebnisausstellung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eintritt in die Erlebnisausstellung - Haus am Strom\" \/>\n<meta property=\"og:description\" content=\"Natur, Energie und Wasser sind die Leitthemen des Haus am Strom. Das erkennt man schon an der Architektur des Hauses, welche einer Donauwelle gleicht. Lernen Sie spielerisch die Artenvielfalt in den Donauleiten kennen, beobachten Sie eine Smaragdeidechse und erzeugen Sie Ihren eigenen Strom! \u00a0 Preise f\u00fcr Eintritt: \u2013 f\u00fcr Erwachsene: 5,00 \u20ac \u2013 f\u00fcr Kinder [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hausamstrom.de\/de\/programm\/buchbares\/dauerbrenner\/eintritt-in-die-erlebnisausstellung\/\" \/>\n<meta property=\"og:site_name\" content=\"Haus am Strom\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hausamstrom\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-14T13:37:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/programm\\\/buchbares\\\/dauerbrenner\\\/eintritt-in-die-erlebnisausstellung\\\/\",\"url\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/programm\\\/buchbares\\\/dauerbrenner\\\/eintritt-in-die-erlebnisausstellung\\\/\",\"name\":\"Eintritt in die Erlebnisausstellung - Haus am Strom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/#website\"},\"datePublished\":\"2016-04-08T12:00:18+00:00\",\"dateModified\":\"2024-09-14T13:37:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/programm\\\/buchbares\\\/dauerbrenner\\\/eintritt-in-die-erlebnisausstellung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/programm\\\/buchbares\\\/dauerbrenner\\\/eintritt-in-die-erlebnisausstellung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/programm\\\/buchbares\\\/dauerbrenner\\\/eintritt-in-die-erlebnisausstellung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programm\",\"item\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/programm\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Buchbares\",\"item\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/programm\\\/buchbares\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Dauerbrenner\",\"item\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/programm\\\/buchbares\\\/dauerbrenner\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Eintritt in die Erlebnisausstellung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/\",\"name\":\"Haus am Strom\",\"description\":\"Umweltbildungsstation im Passauer Donautal. Umweltbildung und Naturschutz f\u00fcr Kinder und Erwachsenen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/#organization\",\"name\":\"Haus am Strom\",\"url\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hausamstrom.de\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Logo-quadratisch-1024x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hausamstrom.de\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Logo-quadratisch-1024x1024.jpg\",\"width\":1024,\"height\":1024,\"caption\":\"Haus am Strom\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hausamstrom\",\"https:\\\/\\\/www.instagram.com\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eintritt in die Erlebnisausstellung - Haus am Strom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hausamstrom.de\/de\/programm\/buchbares\/dauerbrenner\/eintritt-in-die-erlebnisausstellung\/","og_locale":"de_DE","og_type":"article","og_title":"Eintritt in die Erlebnisausstellung - Haus am Strom","og_description":"Natur, Energie und Wasser sind die Leitthemen des Haus am Strom. Das erkennt man schon an der Architektur des Hauses, welche einer Donauwelle gleicht. Lernen Sie spielerisch die Artenvielfalt in den Donauleiten kennen, beobachten Sie eine Smaragdeidechse und erzeugen Sie Ihren eigenen Strom! \u00a0 Preise f\u00fcr Eintritt: \u2013 f\u00fcr Erwachsene: 5,00 \u20ac \u2013 f\u00fcr Kinder [&hellip;]","og_url":"https:\/\/www.hausamstrom.de\/de\/programm\/buchbares\/dauerbrenner\/eintritt-in-die-erlebnisausstellung\/","og_site_name":"Haus am Strom","article_publisher":"https:\/\/www.facebook.com\/hausamstrom","article_modified_time":"2024-09-14T13:37:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hausamstrom.de\/de\/programm\/buchbares\/dauerbrenner\/eintritt-in-die-erlebnisausstellung\/","url":"https:\/\/www.hausamstrom.de\/de\/programm\/buchbares\/dauerbrenner\/eintritt-in-die-erlebnisausstellung\/","name":"Eintritt in die Erlebnisausstellung - Haus am Strom","isPartOf":{"@id":"https:\/\/www.hausamstrom.de\/de\/#website"},"datePublished":"2016-04-08T12:00:18+00:00","dateModified":"2024-09-14T13:37:55+00:00","breadcrumb":{"@id":"https:\/\/www.hausamstrom.de\/de\/programm\/buchbares\/dauerbrenner\/eintritt-in-die-erlebnisausstellung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hausamstrom.de\/de\/programm\/buchbares\/dauerbrenner\/eintritt-in-die-erlebnisausstellung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hausamstrom.de\/de\/programm\/buchbares\/dauerbrenner\/eintritt-in-die-erlebnisausstellung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hausamstrom.de\/de\/"},{"@type":"ListItem","position":2,"name":"Programm","item":"https:\/\/www.hausamstrom.de\/de\/programm\/"},{"@type":"ListItem","position":3,"name":"Buchbares","item":"https:\/\/www.hausamstrom.de\/de\/programm\/buchbares\/"},{"@type":"ListItem","position":4,"name":"Dauerbrenner","item":"https:\/\/www.hausamstrom.de\/de\/programm\/buchbares\/dauerbrenner\/"},{"@type":"ListItem","position":5,"name":"Eintritt in die Erlebnisausstellung"}]},{"@type":"WebSite","@id":"https:\/\/www.hausamstrom.de\/de\/#website","url":"https:\/\/www.hausamstrom.de\/de\/","name":"Haus am Strom","description":"Umweltbildungsstation im Passauer Donautal. Umweltbildung und Naturschutz f\u00fcr Kinder und Erwachsenen.","publisher":{"@id":"https:\/\/www.hausamstrom.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hausamstrom.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.hausamstrom.de\/de\/#organization","name":"Haus am Strom","url":"https:\/\/www.hausamstrom.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.hausamstrom.de\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.hausamstrom.de\/wp-content\/uploads\/2025\/06\/Logo-quadratisch-1024x1024.jpg","contentUrl":"https:\/\/www.hausamstrom.de\/wp-content\/uploads\/2025\/06\/Logo-quadratisch-1024x1024.jpg","width":1024,"height":1024,"caption":"Haus am Strom"},"image":{"@id":"https:\/\/www.hausamstrom.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hausamstrom","https:\/\/www.instagram.com\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.hausamstrom.de\/de\/wp-json\/wp\/v2\/pages\/953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hausamstrom.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hausamstrom.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hausamstrom.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hausamstrom.de\/de\/wp-json\/wp\/v2\/comments?post=953"}],"version-history":[{"count":10,"href":"https:\/\/www.hausamstrom.de\/de\/wp-json\/wp\/v2\/pages\/953\/revisions"}],"predecessor-version":[{"id":12837,"href":"https:\/\/www.hausamstrom.de\/de\/wp-json\/wp\/v2\/pages\/953\/revisions\/12837"}],"up":[{"embeddable":true,"href":"https:\/\/www.hausamstrom.de\/de\/wp-json\/wp\/v2\/pages\/365"}],"wp:attachment":[{"href":"https:\/\/www.hausamstrom.de\/de\/wp-json\/wp\/v2\/media?parent=953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}