{"id":2765,"date":"2017-08-01T16:22:06","date_gmt":"2017-08-01T14:22:06","guid":{"rendered":"https:\/\/hausamstrom.de\/?p=2765"},"modified":"2022-08-17T13:21:36","modified_gmt":"2022-08-17T11:21:36","slug":"wiesenfest-im-garten","status":"publish","type":"post","link":"https:\/\/www.hausamstrom.de\/de\/wiesenfest-im-garten\/","title":{"rendered":"Wiesenfest im Garten"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2100 alignleft\" src=\"https:\/\/hausamstrom.de\/wp-content\/uploads\/2016\/02\/Familienfest-Natur-grenzenlos-82-kl-400x267.jpg\" alt=\"Sommerfest\" width=\"400\" height=\"267\" srcset=\"https:\/\/www.hausamstrom.de\/wp-content\/uploads\/2016\/02\/Familienfest-Natur-grenzenlos-82-kl-400x267.jpg 400w, https:\/\/www.hausamstrom.de\/wp-content\/uploads\/2016\/02\/Familienfest-Natur-grenzenlos-82-kl-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Am Sonntag, den 6. August l\u00e4dt das Haus am Strom in den neuen Garten zum Wiesenfest ein. Ein Programm bunt wie ein Blumenstrau\u00df bietet Gro\u00df und Klein viele M\u00f6glichkeiten, den Lebensraum Wiese und seine Bewohner genauer unter die Lupe zu nehmen. Ab 11 Uhr k\u00f6nnen die Familien mit Donau-R\u00e4tsel und Wiesenblumen-Quiz das Donautal spielerisch erkunden. Auf einem spannenden Wiesenparcours k\u00f6nnen alle ihr Geschick unter Beweis stellen. Um ebenso die Tiere der Wiese n\u00e4her zu bringen, zeigt der Landschaftspflegeverband Interessierten, wie man ein Hotel f\u00fcr Biene Maja und ihre wild lebenden Freundinnen baut. F\u00fcr Unterhaltung sorgt der Geschichtenerz\u00e4hler Andreas Dietz mit Kr\u00f6ti und dem Drachenfest. Dar\u00fcber hinaus l\u00e4dt die Landschaftsarch\u00e4ologie zum Feuermachen und Bogenschie\u00dfen ein. Ein Highlight sind die kostenfreien F\u00fchrungen im Donaukraftwerk Jochenstein, zu denen sich die Teilnehmer an dem Tag anmelden m\u00fcssen. Dabei k\u00f6nnen die f\u00fcnf gro\u00dfen Turbinen des Wasserkraftwerks bestaunt und Schiffe in den Schleusen beobachtet werden. Um sich anschlie\u00dfend wieder zu st\u00e4rken, wird ein vielf\u00e4ltiges Repertoire an regionalen Erzeugnissen angeboten: Besucher werden versorgt mit Krapfen der Biob\u00e4ckerei Grafm\u00fchle oder Bioeis der Firma Stadler. An den weiteren St\u00e4nden k\u00f6nnen die Besucher Erzeugnisse von Kunsthandwerkern bewundern.<\/p>\n<p>Vom Zweitparkplatz in Jochenstein f\u00e4hrt die Feuerwehr die Besucher zum Haus am Strom, da der Weg an der Strasse entlang f\u00fchrt \u2013 f\u00fcr viele ebenfalls eine Attraktion. Die Zufahrt ist nach wie vor f\u00fcr Fahrzeuge ab 2,2 Meter Breite gesperrt, also LKWs und Busse, alle anderen kommen \u00fcber die Baustellenampel zu uns.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am Sonntag, den 6. August l\u00e4dt das Haus am Strom in den neuen Garten zum Wiesenfest ein. Ein Programm bunt wie ein Blumenstrau\u00df bietet Gro\u00df und Klein viele M\u00f6glichkeiten, den Lebensraum Wiese und seine Bewohner genauer unter die Lupe zu nehmen. Ab 11 Uhr k\u00f6nnen die Familien mit Donau-R\u00e4tsel und Wiesenblumen-Quiz das Donautal spielerisch erkunden. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[126],"tags":[],"class_list":["post-2765","post","type-post","status-publish","format-standard","hentry","category-veranstaltungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wiesenfest im Garten - Haus am Strom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hausamstrom.de\/de\/wiesenfest-im-garten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wiesenfest im Garten - Haus am Strom\" \/>\n<meta property=\"og:description\" content=\"Am Sonntag, den 6. August l\u00e4dt das Haus am Strom in den neuen Garten zum Wiesenfest ein. Ein Programm bunt wie ein Blumenstrau\u00df bietet Gro\u00df und Klein viele M\u00f6glichkeiten, den Lebensraum Wiese und seine Bewohner genauer unter die Lupe zu nehmen. Ab 11 Uhr k\u00f6nnen die Familien mit Donau-R\u00e4tsel und Wiesenblumen-Quiz das Donautal spielerisch erkunden. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hausamstrom.de\/de\/wiesenfest-im-garten\/\" \/>\n<meta property=\"og:site_name\" content=\"Haus am Strom\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hausamstrom\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-01T14:22:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-17T11:21:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hausamstrom.de\/wp-content\/uploads\/2016\/02\/Familienfest-Natur-grenzenlos-82-kl-400x267.jpg\" \/>\n<meta name=\"author\" content=\"Haus am Strom Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Haus am Strom Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/wiesenfest-im-garten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/wiesenfest-im-garten\\\/\"},\"author\":{\"name\":\"Haus am Strom Redaktion\",\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/#\\\/schema\\\/person\\\/a3b0cdb507952bbf987dca5ea1cd9bd2\"},\"headline\":\"Wiesenfest im Garten\",\"datePublished\":\"2017-08-01T14:22:06+00:00\",\"dateModified\":\"2022-08-17T11:21:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/wiesenfest-im-garten\\\/\"},\"wordCount\":268,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/wiesenfest-im-garten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hausamstrom.de\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Familienfest-Natur-grenzenlos-82-kl-400x267.jpg\",\"articleSection\":[\"Veranstaltungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/wiesenfest-im-garten\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/wiesenfest-im-garten\\\/\",\"url\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/wiesenfest-im-garten\\\/\",\"name\":\"Wiesenfest im Garten - Haus am Strom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/wiesenfest-im-garten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/wiesenfest-im-garten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hausamstrom.de\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Familienfest-Natur-grenzenlos-82-kl-400x267.jpg\",\"datePublished\":\"2017-08-01T14:22:06+00:00\",\"dateModified\":\"2022-08-17T11:21:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/wiesenfest-im-garten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/wiesenfest-im-garten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/wiesenfest-im-garten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hausamstrom.de\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Familienfest-Natur-grenzenlos-82-kl-400x267.jpg\",\"contentUrl\":\"https:\\\/\\\/hausamstrom.de\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Familienfest-Natur-grenzenlos-82-kl-400x267.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/wiesenfest-im-garten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wiesenfest im Garten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/\",\"name\":\"Haus am Strom\",\"description\":\"Umweltbildungsstation im Passauer Donautal. Umweltbildung und Naturschutz f\u00fcr Kinder und Erwachsenen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/#organization\",\"name\":\"Haus am Strom\",\"url\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hausamstrom.de\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Logo-quadratisch-1024x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hausamstrom.de\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Logo-quadratisch-1024x1024.jpg\",\"width\":1024,\"height\":1024,\"caption\":\"Haus am Strom\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hausamstrom\",\"https:\\\/\\\/www.instagram.com\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/#\\\/schema\\\/person\\\/a3b0cdb507952bbf987dca5ea1cd9bd2\",\"name\":\"Haus am Strom Redaktion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.hausamstrom.de\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Eidechse-Loch-150x150.jpg\",\"url\":\"https:\\\/\\\/www.hausamstrom.de\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Eidechse-Loch-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hausamstrom.de\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Eidechse-Loch-150x150.jpg\",\"caption\":\"Haus am Strom Redaktion\"},\"url\":\"https:\\\/\\\/www.hausamstrom.de\\\/de\\\/author\\\/eidechse-has\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wiesenfest im Garten - Haus am Strom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hausamstrom.de\/de\/wiesenfest-im-garten\/","og_locale":"de_DE","og_type":"article","og_title":"Wiesenfest im Garten - Haus am Strom","og_description":"Am Sonntag, den 6. August l\u00e4dt das Haus am Strom in den neuen Garten zum Wiesenfest ein. Ein Programm bunt wie ein Blumenstrau\u00df bietet Gro\u00df und Klein viele M\u00f6glichkeiten, den Lebensraum Wiese und seine Bewohner genauer unter die Lupe zu nehmen. Ab 11 Uhr k\u00f6nnen die Familien mit Donau-R\u00e4tsel und Wiesenblumen-Quiz das Donautal spielerisch erkunden. [&hellip;]","og_url":"https:\/\/www.hausamstrom.de\/de\/wiesenfest-im-garten\/","og_site_name":"Haus am Strom","article_publisher":"https:\/\/www.facebook.com\/hausamstrom","article_published_time":"2017-08-01T14:22:06+00:00","article_modified_time":"2022-08-17T11:21:36+00:00","og_image":[{"url":"https:\/\/hausamstrom.de\/wp-content\/uploads\/2016\/02\/Familienfest-Natur-grenzenlos-82-kl-400x267.jpg","type":"","width":"","height":""}],"author":"Haus am Strom Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Haus am Strom Redaktion","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hausamstrom.de\/de\/wiesenfest-im-garten\/#article","isPartOf":{"@id":"https:\/\/www.hausamstrom.de\/de\/wiesenfest-im-garten\/"},"author":{"name":"Haus am Strom Redaktion","@id":"https:\/\/www.hausamstrom.de\/de\/#\/schema\/person\/a3b0cdb507952bbf987dca5ea1cd9bd2"},"headline":"Wiesenfest im Garten","datePublished":"2017-08-01T14:22:06+00:00","dateModified":"2022-08-17T11:21:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hausamstrom.de\/de\/wiesenfest-im-garten\/"},"wordCount":268,"commentCount":0,"publisher":{"@id":"https:\/\/www.hausamstrom.de\/de\/#organization"},"image":{"@id":"https:\/\/www.hausamstrom.de\/de\/wiesenfest-im-garten\/#primaryimage"},"thumbnailUrl":"https:\/\/hausamstrom.de\/wp-content\/uploads\/2016\/02\/Familienfest-Natur-grenzenlos-82-kl-400x267.jpg","articleSection":["Veranstaltungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hausamstrom.de\/de\/wiesenfest-im-garten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hausamstrom.de\/de\/wiesenfest-im-garten\/","url":"https:\/\/www.hausamstrom.de\/de\/wiesenfest-im-garten\/","name":"Wiesenfest im Garten - Haus am Strom","isPartOf":{"@id":"https:\/\/www.hausamstrom.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hausamstrom.de\/de\/wiesenfest-im-garten\/#primaryimage"},"image":{"@id":"https:\/\/www.hausamstrom.de\/de\/wiesenfest-im-garten\/#primaryimage"},"thumbnailUrl":"https:\/\/hausamstrom.de\/wp-content\/uploads\/2016\/02\/Familienfest-Natur-grenzenlos-82-kl-400x267.jpg","datePublished":"2017-08-01T14:22:06+00:00","dateModified":"2022-08-17T11:21:36+00:00","breadcrumb":{"@id":"https:\/\/www.hausamstrom.de\/de\/wiesenfest-im-garten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hausamstrom.de\/de\/wiesenfest-im-garten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.hausamstrom.de\/de\/wiesenfest-im-garten\/#primaryimage","url":"https:\/\/hausamstrom.de\/wp-content\/uploads\/2016\/02\/Familienfest-Natur-grenzenlos-82-kl-400x267.jpg","contentUrl":"https:\/\/hausamstrom.de\/wp-content\/uploads\/2016\/02\/Familienfest-Natur-grenzenlos-82-kl-400x267.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hausamstrom.de\/de\/wiesenfest-im-garten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hausamstrom.de\/de\/"},{"@type":"ListItem","position":2,"name":"Wiesenfest im Garten"}]},{"@type":"WebSite","@id":"https:\/\/www.hausamstrom.de\/de\/#website","url":"https:\/\/www.hausamstrom.de\/de\/","name":"Haus am Strom","description":"Umweltbildungsstation im Passauer Donautal. Umweltbildung und Naturschutz f\u00fcr Kinder und Erwachsenen.","publisher":{"@id":"https:\/\/www.hausamstrom.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hausamstrom.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.hausamstrom.de\/de\/#organization","name":"Haus am Strom","url":"https:\/\/www.hausamstrom.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.hausamstrom.de\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.hausamstrom.de\/wp-content\/uploads\/2025\/06\/Logo-quadratisch-1024x1024.jpg","contentUrl":"https:\/\/www.hausamstrom.de\/wp-content\/uploads\/2025\/06\/Logo-quadratisch-1024x1024.jpg","width":1024,"height":1024,"caption":"Haus am Strom"},"image":{"@id":"https:\/\/www.hausamstrom.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hausamstrom","https:\/\/www.instagram.com\/"]},{"@type":"Person","@id":"https:\/\/www.hausamstrom.de\/de\/#\/schema\/person\/a3b0cdb507952bbf987dca5ea1cd9bd2","name":"Haus am Strom Redaktion","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.hausamstrom.de\/wp-content\/uploads\/2016\/02\/Eidechse-Loch-150x150.jpg","url":"https:\/\/www.hausamstrom.de\/wp-content\/uploads\/2016\/02\/Eidechse-Loch-150x150.jpg","contentUrl":"https:\/\/www.hausamstrom.de\/wp-content\/uploads\/2016\/02\/Eidechse-Loch-150x150.jpg","caption":"Haus am Strom Redaktion"},"url":"https:\/\/www.hausamstrom.de\/de\/author\/eidechse-has\/"}]}},"_links":{"self":[{"href":"https:\/\/www.hausamstrom.de\/de\/wp-json\/wp\/v2\/posts\/2765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hausamstrom.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hausamstrom.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hausamstrom.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hausamstrom.de\/de\/wp-json\/wp\/v2\/comments?post=2765"}],"version-history":[{"count":5,"href":"https:\/\/www.hausamstrom.de\/de\/wp-json\/wp\/v2\/posts\/2765\/revisions"}],"predecessor-version":[{"id":11023,"href":"https:\/\/www.hausamstrom.de\/de\/wp-json\/wp\/v2\/posts\/2765\/revisions\/11023"}],"wp:attachment":[{"href":"https:\/\/www.hausamstrom.de\/de\/wp-json\/wp\/v2\/media?parent=2765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hausamstrom.de\/de\/wp-json\/wp\/v2\/categories?post=2765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hausamstrom.de\/de\/wp-json\/wp\/v2\/tags?post=2765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}